{"id":896,"date":"2018-12-12T14:47:20","date_gmt":"2018-12-12T12:47:20","guid":{"rendered":"http:\/\/www.mediterraneofc.gr\/%ce%b5%ce%bd%ce%b4%ce%bf%ce%ba%cf%81%ce%b9%ce%bd%ce%bf%ce%bb%ce%bf%ce%b3%ce%bf%ce%b9-copy\/"},"modified":"2024-11-07T10:15:22","modified_gmt":"2024-11-07T08:15:22","slug":"ent-md","status":"publish","type":"page","link":"https:\/\/mediterraneofc.gr\/en\/ent-md\/","title":{"rendered":"ENT md"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#0067dd&#8221; bg_image=&#8221;406&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; bottom_padding=&#8221;12%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#004aba&#8221; color_overlay_2=&#8221;rgba(0,104,224,0.65)&#8221; overlay_strength=&#8221;0.95&#8243; gradient_direction=&#8221;left_t_to_right_b&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;200&#8243; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; shape_type=&#8221;waves_opacity_alt&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h1&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221;]\n<h1>ENT<\/h1>\n[\/split_line_heading][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;200&#8243;][vc_custom_heading text=&#8221;Personalized healthcare services provided by highly skilled medical doctors who treat each patient with sensitivity and kindness.&#8221; font_container=&#8221;tag:h4|font_size:20px|text_align:left|color:rgba(255%2C255%2C255%2C0.7)|line_height:30px&#8221; google_fonts=&#8221;font_family:Fira%20Sans%3A300%2C300italic%2C400%2C400italic%2C500%2C500italic%2C700%2C700italic|font_style:400%20regular%3A400%3Anormal&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;300&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; font_color=&#8221;#01437d&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;ENT&#8221; font_container=&#8221;tag:h3|font_size:24px|text_align:left|color:%2301437d|line_height:30px&#8221; google_fonts=&#8221;font_family:Fira%20Sans%3A300%2C300italic%2C400%2C400italic%2C500%2C500italic%2C700%2C700italic|font_style:500%20bold%20regular%3A500%3Anormal&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;20&#8243; bottom_padding=&#8221;20&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;small_depth&#8221; column_border_radius=&#8221;5px&#8221; column_link_target=&#8221;_blank&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;grow-in&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;200&#8243; column_link=&#8221;https:\/\/mediterraneofc.gr\/en\/ent-md\/dimitrios-mourkas\/&#8221;][image_with_animation image_url=&#8221;1330&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1730967353560{padding-top: 15px !important;padding-right: 10px !important;padding-bottom: 20px !important;padding-left: 10px !important;}&#8221;]\n<p style=\"text-align: center;\"><strong><span style=\"color: #01437d;\">Dimitrios Mourkas<\/span><\/strong><br \/>\nENT Surgeon<br \/>\nScientific Director ENT<\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_blank&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;grow-in&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;5px&#8221; column_link_target=&#8221;_blank&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_link=&#8221;https:\/\/mediterraneofc.gr\/en\/ent-md\/anna-katsi\/&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#0067dd&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; bottom_padding=&#8221;4%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;rgba(0,74,186,0.3)&#8221; color_overlay_2=&#8221;#0068e0&#8243; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_b_to_right_t&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_position=&#8221;top&#8221; shape_divider_height=&#8221;300&#8243; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;waves_opacity_alt&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;center&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-10-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;200&#8243;][vc_custom_heading text=&#8221;Would you like to make an appointment?&#8221; font_container=&#8221;tag:h3|font_size:24px|text_align:center|color:rgba(255%2C255%2C255%2C0.7)|line_height:30px&#8221; google_fonts=&#8221;font_family:Fira%20Sans%3A300%2C300italic%2C400%2C400italic%2C500%2C500italic%2C700%2C700italic|font_style:400%20regular%3A400%3Anormal&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;see-through-2&#8243; color_override=&#8221;#ffffff&#8221; hover_color_override=&#8221;#ffffff&#8221; hover_text_color_override=&#8221;#000000&#8243; icon_family=&#8221;none&#8221; url=&#8221;https:\/\/mediterraneofc.gr\/en\/contact-us\/&#8221; text=&#8221;CONTACT US&#8221; margin_top=&#8221;30&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#0067dd&#8221; bg_image=&#8221;406&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; bottom_padding=&#8221;12%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#004aba&#8221; color_overlay_2=&#8221;rgba(0,104,224,0.65)&#8221; overlay_strength=&#8221;0.95&#8243; gradient_direction=&#8221;left_t_to_right_b&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;200&#8243; bg_image_animation=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-896","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ENT md | Mediterraneo First Care<\/title>\n<meta name=\"description\" content=\"Primary Medical Services | Accessible Health Services Glyfada | Easy Access For The Disabled And The Elderly | Divers\u03b5 Comfortable Intimateness And Relaxed Atmosphere | Clinical Protocols Secure Systems Advanced Tools Top ServicePathologist,Cardiologist,Gastroenterologist,ENT,Endocrinologist,Dermatologist,Neurosurgeon,Microbiologist,Gynecologist,Obstetrician,Pediatrician,Triplex,Dentist,Pediatric dentist,Orthodontic,Endodontics,Implants,Cosmetic Dentistry,Microbiological examination,Blood tests,Crohn&#039;s disease,Ulcerative colitis,Diabetologist,City Plaza,Glyfada,Polyclinic,Mediterraneo First Care,Mediterraneo,First Care,Doctor,Physician,Test Pap,Infertility,Endometriosis treatment,Aesthetic Gynecology,Repeated miscarriages,Fibromyoma embolism,Triplex heart,Ophthalmologist,Child-ENT,Child-Endocrinology,Pediatric Diabetology,Pediatric Ophthalmologist,Pediatric Dermatologist,Seals,Obstructions,Bleaching,Braces,Denervation,Implants,STRAUMAN\u039d,Cases,Bridges,Dentures,Cloves,Fluoridation,Sealants,Thyroid,Obesity,Diabetes,Pediatric ophthalmological examination,Vision glasses,Myopia,Presbyopia,Pain Clinic,Rheumatoid arthritis,Osteoarthritis,Cancer pains,Headache,Lumbago,Elbow pain,Tennis elbow,Child obesity,Type 2 diabetes,Menopause,Early puberty,Menstrual disorders,Blood tests,Gastro esophageal Reflux,Irritable Bowel Syndrome,Constipation,Holter rhythm,Pressure Holter\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mediterraneofc.gr\/en\/ent-md\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENT md | Mediterraneo First Care\" \/>\n<meta property=\"og:description\" content=\"Primary Medical Services | Accessible Health Services Glyfada | Easy Access For The Disabled And The Elderly | Divers\u03b5 Comfortable Intimateness And Relaxed Atmosphere | Clinical Protocols Secure Systems Advanced Tools Top ServicePathologist,Cardiologist,Gastroenterologist,ENT,Endocrinologist,Dermatologist,Neurosurgeon,Microbiologist,Gynecologist,Obstetrician,Pediatrician,Triplex,Dentist,Pediatric dentist,Orthodontic,Endodontics,Implants,Cosmetic Dentistry,Microbiological examination,Blood tests,Crohn&#039;s disease,Ulcerative colitis,Diabetologist,City Plaza,Glyfada,Polyclinic,Mediterraneo First Care,Mediterraneo,First Care,Doctor,Physician,Test Pap,Infertility,Endometriosis treatment,Aesthetic Gynecology,Repeated miscarriages,Fibromyoma embolism,Triplex heart,Ophthalmologist,Child-ENT,Child-Endocrinology,Pediatric Diabetology,Pediatric Ophthalmologist,Pediatric Dermatologist,Seals,Obstructions,Bleaching,Braces,Denervation,Implants,STRAUMAN\u039d,Cases,Bridges,Dentures,Cloves,Fluoridation,Sealants,Thyroid,Obesity,Diabetes,Pediatric ophthalmological examination,Vision glasses,Myopia,Presbyopia,Pain Clinic,Rheumatoid arthritis,Osteoarthritis,Cancer pains,Headache,Lumbago,Elbow pain,Tennis elbow,Child obesity,Type 2 diabetes,Menopause,Early puberty,Menstrual disorders,Blood tests,Gastro esophageal Reflux,Irritable Bowel Syndrome,Constipation,Holter rhythm,Pressure Holter\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mediterraneofc.gr\/en\/ent-md\/\" \/>\n<meta property=\"og:site_name\" content=\"Mediterraneo First Care\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-07T08:15:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mediterraneofc.gr\/en\/ent-md\/\",\"url\":\"https:\/\/mediterraneofc.gr\/en\/ent-md\/\",\"name\":\"ENT md | Mediterraneo First Care\",\"isPartOf\":{\"@id\":\"https:\/\/mediterraneofc.gr\/en\/#website\"},\"datePublished\":\"2018-12-12T12:47:20+00:00\",\"dateModified\":\"2024-11-07T08:15:22+00:00\",\"description\":\"Primary Medical Services | Accessible Health Services Glyfada | Easy Access For The Disabled And The Elderly | Divers\u03b5 Comfortable Intimateness And Relaxed Atmosphere | Clinical Protocols Secure Systems Advanced Tools Top ServicePathologist,Cardiologist,Gastroenterologist,ENT,Endocrinologist,Dermatologist,Neurosurgeon,Microbiologist,Gynecologist,Obstetrician,Pediatrician,Triplex,Dentist,Pediatric dentist,Orthodontic,Endodontics,Implants,Cosmetic Dentistry,Microbiological examination,Blood tests,Crohn's disease,Ulcerative colitis,Diabetologist,City Plaza,Glyfada,Polyclinic,Mediterraneo First Care,Mediterraneo,First Care,Doctor,Physician,Test Pap,Infertility,Endometriosis treatment,Aesthetic Gynecology,Repeated miscarriages,Fibromyoma embolism,Triplex heart,Ophthalmologist,Child-ENT,Child-Endocrinology,Pediatric Diabetology,Pediatric Ophthalmologist,Pediatric Dermatologist,Seals,Obstructions,Bleaching,Braces,Denervation,Implants,STRAUMAN\u039d,Cases,Bridges,Dentures,Cloves,Fluoridation,Sealants,Thyroid,Obesity,Diabetes,Pediatric ophthalmological examination,Vision glasses,Myopia,Presbyopia,Pain Clinic,Rheumatoid arthritis,Osteoarthritis,Cancer pains,Headache,Lumbago,Elbow pain,Tennis elbow,Child obesity,Type 2 diabetes,Menopause,Early puberty,Menstrual disorders,Blood tests,Gastro esophageal Reflux,Irritable Bowel Syndrome,Constipation,Holter rhythm,Pressure Holter\",\"breadcrumb\":{\"@id\":\"https:\/\/mediterraneofc.gr\/en\/ent-md\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mediterraneofc.gr\/en\/ent-md\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mediterraneofc.gr\/en\/ent-md\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mediterraneofc.gr\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENT md\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mediterraneofc.gr\/en\/#website\",\"url\":\"https:\/\/mediterraneofc.gr\/en\/\",\"name\":\"Mediterraneo First Care\",\"description\":\"Primary Medical Services | Accessible Health Services Glyfada | Easy Access For The Disabled And The Elderly | Divers\u03b5 Comfortable Intimateness And Relaxed Atmosphere | Clinical Protocols Secure Systems Advanced Tools Top\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mediterraneofc.gr\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ENT md | Mediterraneo First Care","description":"Primary Medical Services | Accessible Health Services Glyfada | Easy Access For The Disabled And The Elderly | Divers\u03b5 Comfortable Intimateness And Relaxed Atmosphere | Clinical Protocols Secure Systems Advanced Tools Top ServicePathologist,Cardiologist,Gastroenterologist,ENT,Endocrinologist,Dermatologist,Neurosurgeon,Microbiologist,Gynecologist,Obstetrician,Pediatrician,Triplex,Dentist,Pediatric dentist,Orthodontic,Endodontics,Implants,Cosmetic Dentistry,Microbiological examination,Blood tests,Crohn's disease,Ulcerative colitis,Diabetologist,City Plaza,Glyfada,Polyclinic,Mediterraneo First Care,Mediterraneo,First Care,Doctor,Physician,Test Pap,Infertility,Endometriosis treatment,Aesthetic Gynecology,Repeated miscarriages,Fibromyoma embolism,Triplex heart,Ophthalmologist,Child-ENT,Child-Endocrinology,Pediatric Diabetology,Pediatric Ophthalmologist,Pediatric Dermatologist,Seals,Obstructions,Bleaching,Braces,Denervation,Implants,STRAUMAN\u039d,Cases,Bridges,Dentures,Cloves,Fluoridation,Sealants,Thyroid,Obesity,Diabetes,Pediatric ophthalmological examination,Vision glasses,Myopia,Presbyopia,Pain Clinic,Rheumatoid arthritis,Osteoarthritis,Cancer pains,Headache,Lumbago,Elbow pain,Tennis elbow,Child obesity,Type 2 diabetes,Menopause,Early puberty,Menstrual disorders,Blood tests,Gastro esophageal Reflux,Irritable Bowel Syndrome,Constipation,Holter rhythm,Pressure Holter","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mediterraneofc.gr\/en\/ent-md\/","og_locale":"en_GB","og_type":"article","og_title":"ENT md | Mediterraneo First Care","og_description":"Primary Medical Services | Accessible Health Services Glyfada | Easy Access For The Disabled And The Elderly | Divers\u03b5 Comfortable Intimateness And Relaxed Atmosphere | Clinical Protocols Secure Systems Advanced Tools Top ServicePathologist,Cardiologist,Gastroenterologist,ENT,Endocrinologist,Dermatologist,Neurosurgeon,Microbiologist,Gynecologist,Obstetrician,Pediatrician,Triplex,Dentist,Pediatric dentist,Orthodontic,Endodontics,Implants,Cosmetic Dentistry,Microbiological examination,Blood tests,Crohn's disease,Ulcerative colitis,Diabetologist,City Plaza,Glyfada,Polyclinic,Mediterraneo First Care,Mediterraneo,First Care,Doctor,Physician,Test Pap,Infertility,Endometriosis treatment,Aesthetic Gynecology,Repeated miscarriages,Fibromyoma embolism,Triplex heart,Ophthalmologist,Child-ENT,Child-Endocrinology,Pediatric Diabetology,Pediatric Ophthalmologist,Pediatric Dermatologist,Seals,Obstructions,Bleaching,Braces,Denervation,Implants,STRAUMAN\u039d,Cases,Bridges,Dentures,Cloves,Fluoridation,Sealants,Thyroid,Obesity,Diabetes,Pediatric ophthalmological examination,Vision glasses,Myopia,Presbyopia,Pain Clinic,Rheumatoid arthritis,Osteoarthritis,Cancer pains,Headache,Lumbago,Elbow pain,Tennis elbow,Child obesity,Type 2 diabetes,Menopause,Early puberty,Menstrual disorders,Blood tests,Gastro esophageal Reflux,Irritable Bowel Syndrome,Constipation,Holter rhythm,Pressure Holter","og_url":"https:\/\/mediterraneofc.gr\/en\/ent-md\/","og_site_name":"Mediterraneo First Care","article_modified_time":"2024-11-07T08:15:22+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mediterraneofc.gr\/en\/ent-md\/","url":"https:\/\/mediterraneofc.gr\/en\/ent-md\/","name":"ENT md | Mediterraneo First Care","isPartOf":{"@id":"https:\/\/mediterraneofc.gr\/en\/#website"},"datePublished":"2018-12-12T12:47:20+00:00","dateModified":"2024-11-07T08:15:22+00:00","description":"Primary Medical Services | Accessible Health Services Glyfada | Easy Access For The Disabled And The Elderly | Divers\u03b5 Comfortable Intimateness And Relaxed Atmosphere | Clinical Protocols Secure Systems Advanced Tools Top ServicePathologist,Cardiologist,Gastroenterologist,ENT,Endocrinologist,Dermatologist,Neurosurgeon,Microbiologist,Gynecologist,Obstetrician,Pediatrician,Triplex,Dentist,Pediatric dentist,Orthodontic,Endodontics,Implants,Cosmetic Dentistry,Microbiological examination,Blood tests,Crohn's disease,Ulcerative colitis,Diabetologist,City Plaza,Glyfada,Polyclinic,Mediterraneo First Care,Mediterraneo,First Care,Doctor,Physician,Test Pap,Infertility,Endometriosis treatment,Aesthetic Gynecology,Repeated miscarriages,Fibromyoma embolism,Triplex heart,Ophthalmologist,Child-ENT,Child-Endocrinology,Pediatric Diabetology,Pediatric Ophthalmologist,Pediatric Dermatologist,Seals,Obstructions,Bleaching,Braces,Denervation,Implants,STRAUMAN\u039d,Cases,Bridges,Dentures,Cloves,Fluoridation,Sealants,Thyroid,Obesity,Diabetes,Pediatric ophthalmological examination,Vision glasses,Myopia,Presbyopia,Pain Clinic,Rheumatoid arthritis,Osteoarthritis,Cancer pains,Headache,Lumbago,Elbow pain,Tennis elbow,Child obesity,Type 2 diabetes,Menopause,Early puberty,Menstrual disorders,Blood tests,Gastro esophageal Reflux,Irritable Bowel Syndrome,Constipation,Holter rhythm,Pressure Holter","breadcrumb":{"@id":"https:\/\/mediterraneofc.gr\/en\/ent-md\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mediterraneofc.gr\/en\/ent-md\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mediterraneofc.gr\/en\/ent-md\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mediterraneofc.gr\/en\/"},{"@type":"ListItem","position":2,"name":"ENT md"}]},{"@type":"WebSite","@id":"https:\/\/mediterraneofc.gr\/en\/#website","url":"https:\/\/mediterraneofc.gr\/en\/","name":"Mediterraneo First Care","description":"Primary Medical Services | Accessible Health Services Glyfada | Easy Access For The Disabled And The Elderly | Divers\u03b5 Comfortable Intimateness And Relaxed Atmosphere | Clinical Protocols Secure Systems Advanced Tools Top","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mediterraneofc.gr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/mediterraneofc.gr\/en\/wp-json\/wp\/v2\/pages\/896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediterraneofc.gr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mediterraneofc.gr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mediterraneofc.gr\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/mediterraneofc.gr\/en\/wp-json\/wp\/v2\/comments?post=896"}],"version-history":[{"count":2,"href":"https:\/\/mediterraneofc.gr\/en\/wp-json\/wp\/v2\/pages\/896\/revisions"}],"predecessor-version":[{"id":2110,"href":"https:\/\/mediterraneofc.gr\/en\/wp-json\/wp\/v2\/pages\/896\/revisions\/2110"}],"wp:attachment":[{"href":"https:\/\/mediterraneofc.gr\/en\/wp-json\/wp\/v2\/media?parent=896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}